{"id":11931,"date":"2026-06-23T09:54:19","date_gmt":"2026-06-23T09:54:19","guid":{"rendered":"https:\/\/colosseo.rome.it\/privacy-policy\/"},"modified":"2026-06-23T10:14:03","modified_gmt":"2026-06-23T10:14:03","slug":"informativa-sulla-privacy","status":"publish","type":"page","link":"https:\/\/colosseo.rome.it\/it\/informativa-sulla-privacy\/","title":{"rendered":"Informativa sulla privacy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"11931\" class=\"elementor elementor-11931\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dfbf86d e-flex e-con-boxed e-con e-parent\" data-id=\"dfbf86d\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ba20b4a uppercasefont elementor-widget elementor-widget-heading\" data-id=\"1ba20b4a\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informativa sulla privacy<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57bc7f48 elementor-widget elementor-widget-text-editor\" data-id=\"57bc7f48\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<b>Ultimo aggiornamento: <\/b>23 giugno 2026\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a085147 elementor-widget elementor-widget-text-editor\" data-id=\"2a085147\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La presente Informativa sulla privacy descrive le modalit\u00e0 con cui Web Maremma (\u201cnoi\u201d, \u201cci\u201d, \u201cnostro\u201d) raccoglie, utilizza e protegge i dati personali degli utenti del presente sito web (il \u201cSito web\u201d), in conformit\u00e0 con il Regolamento (UE) 2016\/679 (\u201cGDPR\u201d) e le leggi applicabili in materia di protezione dei dati.<\/p><h2><strong>1. TITOLARE DEL TRATTAMENTO<\/strong><\/h2><p>Il titolare del trattamento \u00e8 Web Maremma.<\/p><p>Per qualsiasi richiesta relativa ai tuoi dati personali, puoi contattarci utilizzando l'indirizzo e-mail indicato nella sezione \"Contatti\" del sito web.<\/p><h2><strong>2. DATI RACCOLTI<\/strong><\/h2><p>Raccogliamo i seguenti tipi di dati:<\/p><h2>DATI DI NAVIGAZIONE<\/h2><p>I dati di navigazione possono includere l'indirizzo IP reso anonimo, il tipo di browser, il sistema operativo, le pagine visitate, la data e l'ora di accesso e l'URL di provenienza.<\/p><h2>COOKIE E IDENTIFICATORI<\/h2><p>Il sito web utilizza cookie tecnici, statistici e di marketing, compresi i cookie di terze parti. Il consenso all'uso dei cookie viene gestito tramite la piattaforma CookieScript.<\/p><p>Per ulteriori dettagli, si prega di consultare la nostra Informativa sui cookie.<\/p><h2>DATI FORNITI VOLONTARIAMENTE DAGLI UTENTI<\/h2><p>Quando ci contatti via e-mail, utilizziamo il tuo indirizzo e-mail esclusivamente per rispondere alla tua richiesta.<\/p><p>Non raccogliamo n\u00e9 trattiamo dati relativi ai pagamenti. Tutte le prenotazioni, gli acquisti o le transazioni vengono effettuati direttamente sul sito web del nostro partner ufficiale Tiqets.com, che agisce in qualit\u00e0 di titolare del trattamento indipendente per tutti i dati relativi a tali operazioni.<\/p><h2><strong>3. FINALIT\u00c0 DEL TRATTAMENTO DEI DATI<\/strong><\/h2><p>I dati possono essere trattati per le seguenti finalit\u00e0: fornitura e miglioramento dei servizi del sito web, elaborazione di statistiche di utilizzo aggregate e anonime, misurazione delle conversioni e delle prestazioni dei link di affiliazione a Tiqets.com e adempimento degli obblighi di legge.<\/p><h2><strong>4. BASE GIURIDICA<\/strong><\/h2><p>Il trattamento dei dati si basa sull'interesse legittimo ai fini dell'analisi aggregata e della sicurezza del sito web, sul consenso dell'utente per i cookie non essenziali e il tracciamento a fini di marketing, nonch\u00e9 sull'adempimento degli obblighi contrattuali o legali, ove applicabile.<\/p><p>Il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p><h2><strong>5. CONSERVAZIONE DEI DATI<\/strong><\/h2><p>I dati di navigazione vengono conservati solo per il tempo necessario al raggiungimento delle finalit\u00e0 per cui sono stati raccolti e, in ogni caso, per un periodo non superiore a 26 mesi per i dati analitici.<\/p><p>I dati di contatto vengono conservati per il tempo necessario alla gestione della richiesta e successivamente cancellati o resi anonimi.<\/p><h2><strong>6. CONDIVISIONE CON TERZE PARTI<\/strong><\/h2><p>Potremmo condividere i dati con i seguenti soggetti esclusivamente per le finalit\u00e0 sopra descritte: Google Analytics, Google Tag Manager e Google Ads per finalit\u00e0 di analisi e marketing; Tiqets B.V., partner ufficiale per le prenotazioni e gli acquisti effettuati tramite link di affiliazione sul sito web; fornitori di servizi di hosting e infrastrutture per l\u2019erogazione dei servizi tecnici; e CookieScript per la gestione del consenso all\u2019uso dei cookie.<\/p><p>Non vendiamo dati personali a terzi.<\/p><h2><strong>7. TRASFERIMENTI AL DI FUORI DELL'UE<\/strong><\/h2><p>Alcuni servizi utilizzati dal sito web, come ad esempio i servizi di Google, potrebbero comportare il trasferimento di dati al di fuori dello Spazio economico europeo.<\/p><p>Tali trasferimenti vengono effettuati sulla base delle clausole contrattuali tipo approvate dalla Commissione europea o di altre garanzie previste dal GDPR.<\/p><h2><strong>8. DIRITTI DELL'UTENTE<\/strong><\/h2><p>In qualsiasi momento, gli utenti possono esercitare i diritti previsti dal GDPR, tra cui l'accesso ai dati personali, la rettifica o la cancellazione, la limitazione del trattamento, l'opposizione al trattamento, la portabilit\u00e0 dei dati, la revoca del consenso e la presentazione di un reclamo al Garante per la protezione dei dati personali all'indirizzo www.garanteprivacy.it.<\/p><p>Per esercitare i propri diritti, \u00e8 possibile contattarci utilizzando l'indirizzo e-mail indicato nella sezione \"Contatti\" del sito web.<\/p><h2><strong>9. COOKIE<\/strong><\/h2><p>Il sito web utilizza cookie tecnici e, previo consenso, cookie analitici e di marketing.<\/p><p>Google Analytics 4 viene utilizzato con l'anonimizzazione dell'IP e la modalit\u00e0 di consenso attivate.<\/p><p>Per ulteriori informazioni, si prega di consultare la nostra Informativa sui cookie.<\/p><h2><strong>10. MODIFICHE ALLA PRESENTE INFORMATIVA SULLA PRIVACY<\/strong><\/h2><p>Ci riserviamo il diritto di aggiornare la presente Informativa sulla privacy in qualsiasi momento. La versione aggiornata sar\u00e0 sempre disponibile su questa pagina, insieme alla data dell'ultima revisione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>This Privacy Policy describes how Web Maremma (\u201cwe\u201d, \u201cus\u201d, \u201cour\u201d) collects, uses, and protects the personal data of users of [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":29,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-11931","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/colosseo.rome.it\/it\/wp-json\/wp\/v2\/pages\/11931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colosseo.rome.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/colosseo.rome.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/colosseo.rome.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/colosseo.rome.it\/it\/wp-json\/wp\/v2\/comments?post=11931"}],"version-history":[{"count":0,"href":"https:\/\/colosseo.rome.it\/it\/wp-json\/wp\/v2\/pages\/11931\/revisions"}],"wp:attachment":[{"href":"https:\/\/colosseo.rome.it\/it\/wp-json\/wp\/v2\/media?parent=11931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}